{"id":683,"date":"2013-10-27T16:57:04","date_gmt":"2013-10-27T15:57:04","guid":{"rendered":"http:\/\/kuminda.org\/?p=683"},"modified":"2013-10-27T16:57:04","modified_gmt":"2013-10-27T15:57:04","slug":"il-world-food-prize-2013-assegnato-alle-multinazionali-degli-ogm","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2013\/10\/il-world-food-prize-2013-assegnato-alle-multinazionali-degli-ogm\/","title":{"rendered":"Il World Food Prize 2013 assegnato alle multinazionali degli OGM"},"content":{"rendered":"<p>Il World Food Prize 2013 \u00e8 stato assegnato al vicepresidente esecutivo della Monsanto<!--more-->e sviluppatore del primo seme di soia geneticamente modificato. Robert Fraley condivider\u00e0 il premio con due colleghi biotecnologi, uno della societ\u00e0 biotech Sgenta e l&#8217;altro dell&#8217;Insitute of Plant Biotechnology Outreach.<\/p>\n<p>I commenti e le proteste negative non sono pochi: negli Stati Uniti \u00e8 nato il movimento Occupy The World Food Prize che sta attuando in tutto il territorio inziative per sensibilizzare i cittadini riguardo le conseguenze degli OGM.<\/p>\n<p>L&#8217;articolo completo con maggiori approfondimenti \u00e8 stato pubblicato su<a href=\"http:\/\/www.ilcambiamento.it\/multinazionali\/alimentazione_nobel_cibo_multinazionali_ogm.html\"> Il Cambiamento<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il World Food Prize 2013 \u00e8 stato assegnato al vicepresidente esecutivo della Monsanto<\/p>\n","protected":false},"author":2,"featured_media":685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[24,11,27,38,44,30,29,31,9],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/683"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":2,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"predecessor-version":[{"id":686,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/683\/revisions\/686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/685"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}