{"id":3799,"date":"2020-04-03T04:51:17","date_gmt":"2020-04-03T03:51:17","guid":{"rendered":"http:\/\/kuminda.org\/?p=3799"},"modified":"2020-10-14T09:41:08","modified_gmt":"2020-10-14T08:41:08","slug":"laboratorio-itinerante-fra-cibo-e-cultura-racconto-della-tappa-marocco-1-parte","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2020\/04\/laboratorio-itinerante-fra-cibo-e-cultura-racconto-della-tappa-marocco-1-parte\/","title":{"rendered":"Laboratorio itinerante fra cibo e cultura &#8211; racconto della tappa Marocco &#8211; 1 parte"},"content":{"rendered":"<p>La prima tappa di &#8220;Cibo per tutti. Laboratorio itinerante fra cibo e cultura&#8221; si \u00e8 conclusa pi\u00f9 di un mese fa, appena prima che l&#8217;attuale pandemia modificasse il nostro modo di partecipare alla cosa pubblica.<\/p>\n<p>In questo momento, forse, abbiamo bisogno di ripercorrere le attivit\u00e0 che ci hanno visto insieme a ragionare, emozionarci, ascoltare e raccontare.<\/p>\n<p>Abbiamo bisogno di sapere che torneremo a stare a fianco a fianco per progettare e costruire ponti fra territori distanti, all&#8217;insegna di comunit\u00e0 sempre pi\u00f9 eque e aperte,\u00a0e che torneremo a usare l&#8217;accezione positiva del verbo &#8220;contaminare&#8221;, cos\u00ec legato al verbo &#8220;accogliere&#8221; da suggerirci che possiamo fare spazio all&#8217;altro solo se disponibili a farci toccare, &#8220;inquinare&#8221; e cambiare, anche solo un poco, da lui, dai suoi modi di guardare questo stesso nostro mondo<em>.\u00a0<\/em><\/p>\n<p>Guardate il video in pillole<\/p>\n<p><iframe loading=\"lazy\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/CLhxEk26s4Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>e nella versione integrale<\/p>\n<p><iframe loading=\"lazy\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/WrAlWCbloVw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Progetto di CSV Emilia e rete\u00a0Cibopertutti\u00a0nell&#8217;ambito di Parma 2020 &#8211; Capitale Italiana della Cultura<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prima tappa di &#8220;Cibo per tutti. Laboratorio itinerante fra cibo e cultura&#8221; si \u00e8 conclusa pi\u00f9 di un mese fa, appena prima che l&#8217;attuale pandemia modificasse il nostro modo di partecipare alla cosa pubblica. In questo momento, forse, abbiamo bisogno di ripercorrere le attivit\u00e0 che ci hanno visto insieme a ragionare, emozionarci, ascoltare e<\/p>\n","protected":false},"author":3,"featured_media":3801,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[41,14,10,37,65,16,36,45,42,34,44,46,47,17,40,31,1],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3799"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=3799"}],"version-history":[{"count":2,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3799\/revisions"}],"predecessor-version":[{"id":3802,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3799\/revisions\/3802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/3801"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=3799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=3799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=3799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}