{"id":3758,"date":"2020-02-06T08:09:32","date_gmt":"2020-02-06T07:09:32","guid":{"rendered":"http:\/\/kuminda.org\/?p=3758"},"modified":"2020-02-10T17:19:31","modified_gmt":"2020-02-10T16:19:31","slug":"il-te-delle-signore-a-sorbolo-16-febbraio-2020","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2020\/02\/il-te-delle-signore-a-sorbolo-16-febbraio-2020\/","title":{"rendered":"Il t\u00e8 delle signore&#8230;ma anche dei signori &#8211; a Sorbolo &#8211; 16 Febbraio 2020"},"content":{"rendered":"<p>Un sodalizio che si rinnova &#8211; il Marocco e Sorbolo<\/p>\n<p><!--more--><\/p>\n<p>Scarica la locandina <a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Sorbolo.pdf\">Cibo per tutti Marocco_Sorbolo<\/a><\/p>\n<p>Una tazza di t\u00e8 che scandisce il tempo, dolcetti cucinati con ingredienti, storie e provenienze differenti, racconti, esperienze, musica.<\/p>\n<p>Tra un sorso, una storia e una canzone Sorbolo ospiter\u00e0 il Marocco. Domenica 16 Febbraio 2020, alle ore 17.00, la Sala Benassi del Centro Sociale di via Gruppini 4 &#8211; Sorbolo si riempie di profumi e colori marocchini.\u00a0 L\u2019associazione Donne di qua e di l\u00e0, insieme alla delegazione marocchina narrer\u00e0 il rituale del t\u00e8 tra assaggi e musiche.<\/p>\n<p>Alle ore 18.00 sar\u00e0 possibile conoscere le esperienze della preziosa delegazione marocchina che ci parler\u00e0 de &#8220;L&#8217;olio d&#8217;argan fra tradizioni e modernit\u00e0: come si produce, gli usi e le propriet\u00e0&#8221;.<\/p>\n<p>Ingresso libero e gratuito<\/p>\n<p><a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Sorbolo.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-3753\" src=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Sorbolo-166x300.jpg\" alt=\"\" width=\"166\" height=\"300\" srcset=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Sorbolo-166x300.jpg 166w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Sorbolo-768x1387.jpg 768w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Sorbolo-567x1024.jpg 567w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Sorbolo.jpg 886w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un sodalizio che si rinnova &#8211; il Marocco e Sorbolo<\/p>\n","protected":false},"author":3,"featured_media":3762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24,27,41,14,10,36,45,42,44,46,47,26,9],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3758"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=3758"}],"version-history":[{"count":3,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3758\/revisions"}],"predecessor-version":[{"id":3779,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3758\/revisions\/3779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/3762"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=3758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=3758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=3758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}