{"id":3737,"date":"2020-02-06T08:14:25","date_gmt":"2020-02-06T07:14:25","guid":{"rendered":"http:\/\/kuminda.org\/?p=3737"},"modified":"2020-02-10T17:18:43","modified_gmt":"2020-02-10T16:18:43","slug":"i-te-delle-signore-dall11-al-15-febbraio-2020","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2020\/02\/i-te-delle-signore-dall11-al-15-febbraio-2020\/","title":{"rendered":"I t\u00e8 delle signore &#8230; ma anche dei signori &#8211; dall&#8217;11 al 15 Febbraio 2020"},"content":{"rendered":"<p>Il rituale del t\u00e8 marocchino alle 17 alla Farmacia San Filippo Neri in vicolo S. Tiburzio &#8211; Parma<\/p>\n<p><!--more--><\/p>\n<p>Si dice t\u00e8 ma si sentono mille suoni e profumi. In Marocco la preparazione del t\u00e8 prevede un\u00a0paziente e affascinante rituale ricco di abilit\u00e0. Abbiamo deciso di riproporlo ogni giorno per l&#8217;arrivo della delegazione dal Marocco nell&#8217;ambito dei &#8220;Laboratori itineranti fra cibo e cultura&#8221;.<\/p>\n<p>Scarica la locandina <a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Te\u0300-delle-signore.pdf\">Cibo per tutti Marocco_Te\u0300 delle signore<\/a><\/p>\n<p>Ogni giorno, dall&#8217;11 al 15 Febbraio 2020 la Farmacia San Filippo Neri in vicolo S. Tiburzio &#8211; Parma ospiter\u00e0 &#8220;Il t\u00e8 delle signore&#8221;. Si inizia sempre alle 17 fra letture e racconti della delegazione, sorseggiando la profumatissima bevanda alla menta insieme ai dolcetti marocchini. Il tutto preparato e servito secondo i gesti della tradizione. Ogni giorno seguir\u00e0, alle 18, una conversazione su un tema diverso dove alle voci dal Marocco si accosteranno approfondimenti e testimonianze di esperienze di spicco locali.\u00a0 L\u201911 febbraio si parler\u00e0 di Seconde generazioni, vivere fra due culture, il 12 febbraio \u201cDall&#8217;olio d&#8217;argan del Marocco alla lavanda di Parma: usi, propriet\u00e0, assaggi col naso e con la bocca\u201d; gioved\u00ec 13 febbraio \u201cDella cucina marocchina. Tradizioni e consuetudini mediterranee\u201d. Il giorno di San Valentino si celebrer\u00e0 l\u2019amore con le Conversazioni sul libro \u201cI sessanta nomi dell&#8217;amore\u201d in presenza dell\u2019autore Tahar Lamri e con letture di brani accompagnati da assaggi di cibi e profumi. Sabato invece il focus sar\u00e0 sul \u201cCibo e ospitalit\u00e0 nelle tradizioni religiose\u201d. L\u2019ultimo T\u00e8 delle signore sar\u00e0 a Sorbolo, nella sala Benassi, sempre dalle 17 con il Coro del Centro Interculturale. Dalle 18 il tema sar\u00e0 \u201cL&#8217;olio d&#8217;argan fra tradizione e modernit\u00e0: come si produce, gli usi, le propriet\u00e0\u201d.<\/p>\n<p>Ingresso libero e gratuito<\/p>\n<p><a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Te\u0300-delle-signore.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-3738\" src=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Te\u0300-delle-signore-166x300.jpg\" alt=\"\" width=\"166\" height=\"300\" srcset=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Te\u0300-delle-signore-166x300.jpg 166w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Te\u0300-delle-signore-768x1388.jpg 768w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Te\u0300-delle-signore-567x1024.jpg 567w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2020\/02\/Cibo-per-tutti-Marocco_Te\u0300-delle-signore.jpg 1020w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il rituale del t\u00e8 marocchino alle 17 alla Farmacia San Filippo Neri in vicolo S. Tiburzio &#8211; Parma<\/p>\n","protected":false},"author":3,"featured_media":3667,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24,41,14,36,45,44,46,40,9,1],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3737"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=3737"}],"version-history":[{"count":4,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3737\/revisions"}],"predecessor-version":[{"id":3778,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3737\/revisions\/3778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/3667"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=3737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=3737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=3737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}