{"id":3636,"date":"2017-10-16T12:51:24","date_gmt":"2017-10-16T11:51:24","guid":{"rendered":"http:\/\/kuminda.org\/?p=3636"},"modified":"2017-10-16T12:51:54","modified_gmt":"2017-10-16T11:51:54","slug":"boschetto-dei-sorbi-thomas-sankara","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2017\/10\/boschetto-dei-sorbi-thomas-sankara\/","title":{"rendered":"Boschetto dei Sorbi Thomas Sankara"},"content":{"rendered":"<p>Kuminda Sorbolo continua il 21 ottobre con l&#8217;intitolazione di un&#8217;area verde comunale a Thomas Sankara<!--more--><\/p>\n<p style=\"text-align: center;\"><em>&#8220;Ogni gioia ha il suo albero, ogni albero \u00e8 una gioia&#8221;<\/em><\/p>\n<p style=\"text-align: center;\"><em>Thomas Sankara<\/em><\/p>\n<p style=\"text-align: left;\">Il ricordo di Sankara continua, dopo la serata con cena del 20 ottobre, la mattina del 21 ottobre con l&#8217;intitolazione di un&#8217;area verde comunale di Sorbolo a Thomas Sankara.<\/p>\n<p style=\"text-align: left;\"><strong>ORE 11:00 presso l&#8217;AEREA VERDE di Via XIV Maggio di Sorbolo<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>BOSCHETTO DEI SORBI THOMAS SANKARA<\/strong><\/p>\n<p style=\"text-align: left;\">con interventi di:<\/p>\n<p style=\"text-align: left;\"><em><strong>Aluisi Tosolini<\/strong><\/em> &#8211; Dirigente Scolastico del Liceo Attilio Bertolucci di Parma e autore del libro &#8220;Thomas Sankara: una speranza recisa&#8221; 1988<\/p>\n<p style=\"text-align: left;\"><strong><em>Abdu Yabre<\/em><\/strong> &#8211; Presidente della Comunit\u00e0 Burkinab\u00e9 di Reggio Emilia<\/p>\n<p style=\"text-align: left;\"><strong><em>Cleophas Dioma<\/em><\/strong> &#8211; Associazione Le Reseau<\/p>\n<p style=\"text-align: left;\"><strong>classi terze della scuola secondaria di primo grado di Sorbolo<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Marco Minardi<\/strong> &#8211;\u00a0 Direttore dell&#8217;Istituto\u00a0Storico della Resistenza e dell&#8217;Et\u00e0 Contemporanea<\/p>\n<p style=\"text-align: left;\"><strong>Cristina Valenti<\/strong> &#8211; Assessore alla Cultura del Comune di Sorbolo<\/p>\n<p style=\"text-align: left;\"><strong>Sara Boriani<\/strong> &#8211; Assessore all&#8217;Ambiente e ai Servizi Educativi del Comune di Sorbolo<\/p>\n<p style=\"text-align: left;\">L&#8217;iniziativa \u00e8\u00a0organizzata da: Comune di Sorbolo, Istituto Comprensivo di Sorbolo, Cooperativa Nativa, Istituto\u00a0Storico della Resistenza e dell&#8217;Et\u00e0 Contemporanea, Ottobre Africano e\u00a0 con il sostegno di Coop Alleanza 3.0.<\/p>\n<p><a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/10\/Sorbolo-21-ottobre.png\"><img loading=\"lazy\" class=\"size-medium wp-image-3637 aligncenter\" src=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/10\/Sorbolo-21-ottobre-213x300.png\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/10\/Sorbolo-21-ottobre-213x300.png 213w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/10\/Sorbolo-21-ottobre-768x1084.png 768w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/10\/Sorbolo-21-ottobre-726x1024.png 726w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/10\/Sorbolo-21-ottobre-600x847.png 600w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/10\/Sorbolo-21-ottobre.png 1092w\" sizes=\"(max-width: 213px) 100vw, 213px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kuminda Sorbolo continua il 21 ottobre con l&#8217;intitolazione di un&#8217;area verde comunale a Thomas Sankara<\/p>\n","protected":false},"author":2,"featured_media":3638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[45],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3636"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=3636"}],"version-history":[{"count":1,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3636\/revisions"}],"predecessor-version":[{"id":3639,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3636\/revisions\/3639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/3638"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=3636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=3636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=3636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}