{"id":3619,"date":"2017-09-07T12:56:34","date_gmt":"2017-09-07T11:56:34","guid":{"rendered":"http:\/\/kuminda.org\/?p=3619"},"modified":"2017-09-07T13:00:01","modified_gmt":"2017-09-07T12:00:01","slug":"zoubida-charrouf-largan-la-donna-saperi","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2017\/09\/zoubida-charrouf-largan-la-donna-saperi\/","title":{"rendered":"Zoubida Charrouf &#8230; l&#8217;argan, la donna e i saperi"},"content":{"rendered":"<p>In occasione del seminario &#8220;Agricolture sostenibili per comunit\u00e0 solidali&#8221; tenutosi a Parma il 28 e 29 Agosto, la rete Ciboepertutti, l&#8217;Associazione Mani e l&#8217;Associazione Donne di qua e di l\u00e0 hanno ospitato Zoubida Charrouf, docente del Chimica Vegetale e di Sintesi Organica e Bio-Organica all&#8217;Universit\u00e0 di Rabat &#8211; Marocco.<\/p>\n<p>Zoubida Charrouf \u00e8 considerata la madre dell&#8217;argan.\u00a0Il suo impegno \u00e8 stato talmente importante che rese possibile la diffusione della conoscenza e dell&#8217;apprezzamento di questo prodotto sia nel suo paese che fuori.<\/p>\n<p>Clicca <a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/Zoubida-Charrouf.pdf\">QUI<\/a> per la relazione di Zoubida Charrouf al seminario &#8220;Agricolture sostenibili per comunit\u00e0 solidali&#8221;.<\/p>\n<p>Nel pomeriggio del 29 Agosto, l&#8217;associazione Donne di qua e di l\u00e0 ha organizzato un incontro dal titolo &#8220;Parma e Rabat. Due territori a confronto per un focus sulla condizione femminile&#8221; tra Zoubida Charrouf, l&#8217;Assessora alle Pari Opportunit\u00e0 del Comune di Parma\u00a0Nicoletta Paci, \u00a0la Presidente della Rete Cibopertutti Elena Olivieri, la rappresentante del Centro Universitario Cooperazione Internazionale dell&#8217;Universit\u00e0 di Parma Nadia Monicelli e alcuni membri del Consiglio Comunale di Parma. L&#8217;incontro, moderato da Matilde Marchesini dell&#8217;Associazione Mani, \u00e8 stato un momento di conoscenza importante e propedeutico al viaggio in Marocco che vedr\u00e0 una delegazione di sei donne di Parma (tra cui Mounia Elfasi &#8211; Presidente di Donne di qua e di l\u00e0 e Matilde Marchesini di Ass. Mani) andare a rendere visita a vari luoghi significativi di produzione di saperi in Marocco.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/locandinda-incontro-parma-rabat.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-3617\" src=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/locandinda-incontro-parma-rabat-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/locandinda-incontro-parma-rabat-212x300.jpg 212w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/locandinda-incontro-parma-rabat-768x1087.jpg 768w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/locandinda-incontro-parma-rabat-724x1024.jpg 724w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/locandinda-incontro-parma-rabat-600x849.jpg 600w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/locandinda-incontro-parma-rabat.jpg 1116w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a> <a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/programma-zoubida-charruf.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-3618\" src=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/programma-zoubida-charruf-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/programma-zoubida-charruf-212x300.jpg 212w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/programma-zoubida-charruf-768x1086.jpg 768w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/programma-zoubida-charruf-724x1024.jpg 724w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/programma-zoubida-charruf-600x849.jpg 600w, https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2017\/09\/programma-zoubida-charruf.jpg 1190w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione del seminario &#8220;Agricolture sostenibili per comunit\u00e0 solidali&#8221; tenutosi a Parma il 28 e 29 Agosto, la rete Ciboepertutti, l&#8217;Associazione Mani e l&#8217;Associazione Donne di qua e di l\u00e0 hanno ospitato Zoubida Charrouf, docente del Chimica Vegetale e di Sintesi Organica e Bio-Organica all&#8217;Universit\u00e0 di Rabat &#8211; Marocco. Zoubida Charrouf \u00e8 considerata la madre<\/p>\n","protected":false},"author":3,"featured_media":3620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[45,47,59],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3619"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=3619"}],"version-history":[{"count":1,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3619\/revisions"}],"predecessor-version":[{"id":3621,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/3619\/revisions\/3621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/3620"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=3619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=3619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=3619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}