{"id":2973,"date":"2016-06-13T09:31:38","date_gmt":"2016-06-13T08:31:38","guid":{"rendered":"http:\/\/kuminda.org\/?p=2973"},"modified":"2016-09-23T15:33:27","modified_gmt":"2016-09-23T14:33:27","slug":"le-banane-le-insalata-dole","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2016\/06\/le-banane-le-insalata-dole\/","title":{"rendered":"Le banane e le insalata di Dole"},"content":{"rendered":"<p>Dole una delle pi\u00f9 grandi multinazionali del cibo<!--more--><\/p>\n<p>Un articolo di Info Comune<\/p>\n<p>&#8220;Nei giorni scorsi la Dole, tra le pi\u00f9 potenti multinazionali del cibo (a cominciare dalla banane), ha ammesso di essere sotto inchiesta da parte del Dipartimento statunitense della Giustizia per la vendita di alimenti contaminati a causa delle insalate infette da un focolaio di listeriosi che avrebbe contaminato, tra settembre 2015 e gennaio 2016, almeno trenta persone e provocato la morte di quattro. Secondo molti l\u2019inchiesta provocher\u00e0 guai economici seri all\u2019impresa. Ma la Dole, ricordano quelli di Adbusters, resta nota soprattutto per le denunce dei contadini latinoamericani, vittime dei pesticidi imposti fino a pochi anni fa dalla multinazionale californiana. In realt\u00e0, nei movimenti di consumo critico la Dole \u00e8 conosciuta anche per il documentario Bananas!* e per la straordinaria campagna di boicottaggio che ha visto un paese intero, la Svezia, ribellarsi. E vincere&#8221;<\/p>\n<p>L&#8217;<a href=\"http:\/\/comune-info.net\/2016\/06\/il-popolo-contro-dole\/\">articolo intero<\/a> e per approfondire:<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/3VYPQ6jJKWY\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dole una delle pi\u00f9 grandi multinazionali del cibo<\/p>\n","protected":false},"author":2,"featured_media":2974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,10,39,44,13,9],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2973"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=2973"}],"version-history":[{"count":1,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2973\/revisions"}],"predecessor-version":[{"id":2975,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2973\/revisions\/2975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/2974"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=2973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=2973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}