{"id":2797,"date":"2015-11-06T14:42:39","date_gmt":"2015-11-06T13:42:39","guid":{"rendered":"http:\/\/kuminda.org\/?p=2797"},"modified":"2015-12-16T12:41:52","modified_gmt":"2015-12-16T11:41:52","slug":"grazie","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2015\/11\/grazie\/","title":{"rendered":"I grazie di Kuminda"},"content":{"rendered":"<p>Anche quest&#8217;anno Kuminda \u00e8 stato possibile grazie a tante persone<!--more--><\/p>\n<p>GRAZIE a chi, senza comparire sul programma, ha reso possibile, con seriet\u00e0 e passione, anche quest\u2019anno la realizzazione di Kuminda. I volontari e le volontarie:<\/p>\n<p>Adalgisa Bertolini<\/p>\n<p>Alessandra Frigeri<\/p>\n<p>Amagnan Dossou Landry<\/p>\n<p>Amina Hadjameur<\/p>\n<p>Andrea Giubellini<\/p>\n<p>Beatrice Meli<\/p>\n<p>Caterina Ambanelli<\/p>\n<p>Chrysi Tsapekou<\/p>\n<p>Daniel Flores<\/p>\n<p>Erika Farina<\/p>\n<p>Fabio Camassa<\/p>\n<p>Francesco Del Grano<\/p>\n<p>Francesco<\/p>\n<p>Giulia Barbacini<\/p>\n<p>Giulia Gandolfi<\/p>\n<p>Giulia Malpeli<\/p>\n<p>Linda Gazzea<\/p>\n<p>Luca Dotti<\/p>\n<p>Luca Reggiani<\/p>\n<p>Margherita Folzani<\/p>\n<p>Rocco Bonforte<\/p>\n<p>Rosanna Panizza<\/p>\n<p>Rosine Sizefoka<\/p>\n<p>Rossella Coppola<\/p>\n<p>Sinan Ulas<\/p>\n<p>Tiziana Coluccia<\/p>\n<p>Valentina Gini<\/p>\n<p>Vincenzo Fornari<\/p>\n<p>Vittoria Pattacini<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table width=\"625\">\n<tbody>\n<tr>\n<td width=\"625\">Ringraziamo anche tutti coloro che hanno contribuito al programma di Kuminda portando esperienze, organizzando iniziative o accogliendole nei propri spazi: si tratta di gruppi, associazioni, cooperative sociali, comuni, scuole, persone, docenti, attivisti, artisti, curiosi. Gente appassionata e intelligente.<\/p>\n<p>Grazie di cuore<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;anno Kuminda \u00e8 stato possibile grazie a tante persone<\/p>\n","protected":false},"author":6,"featured_media":2828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[45],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2797"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=2797"}],"version-history":[{"count":9,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2797\/revisions"}],"predecessor-version":[{"id":2853,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2797\/revisions\/2853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/2828"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=2797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=2797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}