{"id":2113,"date":"2014-12-11T10:32:19","date_gmt":"2014-12-11T09:32:19","guid":{"rendered":"http:\/\/kuminda.org\/?p=2113"},"modified":"2014-12-11T10:33:06","modified_gmt":"2014-12-11T09:33:06","slug":"report-ttip-cibo-e-agricoltura","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2014\/12\/report-ttip-cibo-e-agricoltura\/","title":{"rendered":"Report: TTIP, cibo e agricoltura"},"content":{"rendered":"<p>Alcune ragioni per fermare il TTIP (Transatlantic Trade and Investment Partnership) il trattato di liberalizzazione commerciale tra UE e USA <!--more--><\/p>\n<p>Consigliamo la lettura del report scritto da Fair Watch riguardo le relazioni tra il TTIP e agricoltura, sovranit\u00e0 alimentare, cibo, OGM. <a href=\"https:\/\/multiculturale.it\/kuminda\/wp-content\/uploads\/2014\/12\/ttip_agri-fairwatch.pdf\">ttip_agri-fairwatch<\/a><\/p>\n<p>Dal sito: <a href=\"http:\/\/stop-ttip-italia.net\/info\/\">www.stop-ttip-italia.net<\/a><\/p>\n<p>&#8220;Il TTIP, Transatlantic Trade and Investment Partnership, il trattato di libero scambio tra Unione Europea e Stati Uniti d\u2019America attualmente oggetto di negoziati volutamente segreti, \u00e8 qualcosa di pi\u00f9 di una semplice trattativa di liberalizzazione commerciale.<br \/>\nE\u2019 l\u2019ennesimo attacco frontale che vede lobby economiche, Governi e poteri forti accanirsi su quello che rimane dei diritti del lavoro, della persona, dell\u2019ambiente e di cittadinanza dopo anni di crisi economica e finanziaria, in un pi\u00f9 ampio tentativo di disarticolare le conquiste di anni di lotte sociali con le politiche di austerity e di redistribuzione del reddito verso l\u2019alto.<br \/>\nIl negoziato TTIP, lanciato ufficialmente nel luglio 2013 e portato avanti in modo opaco e segreto dalla Commissione europea e dall\u2019Amministrazione statunitense in vista di una sua possibile conclusione a fine 2014, disegna un quadro di pesante deregolamentazione dove obiettivo principale non saranno t anto le barriere tariffarie, gi\u00e0 abbastanza basse, ma quelle non tariffarie, che riguardano gli standard di sicurezza e di qualit\u00e0 di aspetti sostanziali della vita di tutti i cittadini: l\u2019alimentazione, l&#8217;istruzione e la cultura, i servizi sanitari, i servizi sociali, le tutele e la sicurezza sul lavoro.<br \/>\nCon l\u2019alibi di un\u2019omogeneizzazione delle normative e la falsa illusione di risollevare l\u2019economia dell\u2019Europa, si assister\u00e0 ad una progressiva corsa verso il basso in cui saranno i cittadini e l\u2019ambient e a farne principalmente le spese in un processo che porter\u00e0 alla progressiva mercificazione di servizi pubblici e di beni comuni. Un rischio che viene tenuto sotto traccia a causa di trattative svolte a porte chiuse, sotto la<br \/>\nforte pressione delle lobby delle industrie private senza un coinvolgimento efficace dei Parlamenti e del Congresso e senza che i cittadini vengano adeguatamente informati.<br \/>\nTra i principali obiettivi del negoziato, c\u2019\u00e8 la tutela dell\u2019investitore e della propriet\u00e0 privata, grazie alla costituzione di un organismo di risoluzione delle controversie, un vero e proprio arbitrato internazionale, a cui le aziende potranno appellarsi per rivalersi su Governi colpevoli, a loro dire, di aver ostacolato la loro corsa al profitto. Qualsiasi regolamentazione pubblica che tuteli i diritti sociali, economici ed ambientali, con la scusa della tutela della competizione e degli investimenti, rischier\u00e0 di soccombere dinanzi alle esigenze delle aziende e dei mercati, tutelate da sentenze che saranno a tutti gli effetti inappellabili. Scenari che si sono gi\u00e0 avverati nell&#8217;ambito di altri trattati di libero scambio come il Nafta, o che hanno permesso a una multinazionale energetica come la Vattenfall di citare in giudizio il Governo tedesco per la decisione<br \/>\ndella Germania di chiudere le proprie centrali nucleari.<\/p>\n<p><strong>Alcuni buoni motivi per fermare il TTIP<\/strong><br \/>\n<strong>Sicurezza alimentare:<\/strong><br \/>\nle norme europee su pesticidi, Ogm, carne agli ormoni e pi\u00f9 in generale sulla qualit\u00e0 de gli alimenti, pi\u00f9 restrittive di quelle americane e internazionali, potrebbero essere condannate come \u201cbarriere commerciali illegali\u201d;<br \/>\n<strong>Acqua ed energia:<\/strong><br \/>\nsono settori a rischio privatizzazione. Tutte quelle comunit\u00e0 che si dovessero opporre potrebbero essere accusate di distorsione del mercato<br \/>\n<strong>Servizi pubblici:<\/strong><br \/>\nil TTIP limiterebbe il potere degli Stati nell\u2019organizzare i servizi pubblici come la sanit\u00e0, i trasporti, l&#8217;istruzione, i servizi idrici, educativi e metterebbe a rischio l\u2019accesso per tutti a tali servizi a vantaggio di una privatizzazione che rischia di escludere i meno privilegiati<br \/>\n<strong>Diritti del lavoro:<\/strong><br \/>\nla legislazione sul lavoro, gi\u00e0 drasticamente deregolamentata dalle politiche di austerity dell\u2019Unione Europea, verrebbe ulteriormente attaccata i<br \/>\nn quanto potrebbe essere considerata \u201cbarriera non tariffaria\u201d da rimuovere<br \/>\n<strong>Finanza:<\/strong><br \/>\nil trattato comporterebbe l\u2019impossibilit\u00e0 di qualsivoglia controllo sui movimenti di capitali e sulla speculazione bancaria e finanziaria;<br \/>\n<strong>Brevetti e propriet\u00e0 intellettuale:<\/strong><br \/>\nla difesa dei diritti di propriet\u00e0 delle imprese sui brevetti metterebbe a rischio la disponibilit\u00e0 di beni essenziali, quali ad esempio i medicinali generici. Cos\u00ec come la difesa dei diritti di propriet\u00e0 intellettuale possono limitare la diffusione della conoscenza e delle espressioni artistiche;<br \/>\n<strong>Gas di scisto:<\/strong><br \/>\nil fracking, gi\u00e0 bandito in Francia per rischi ambientali, potrebbe diventare una pratica tutelata dal diritto. Le compagnie estrattive interessate ad operare in questo settore potrebbero chiedere risarcimenti agli Stati che ne impediscono l\u2019utilizzo. In questo modo si violerebbe il principio di precauzione sancito dall\u2019Unione Europea, incentivando iniziative economiche che mettono in pericolo la salute umana,<br \/>\nanimale e vegetale, nonch\u00e9 la protezione dell\u2019ambiente;<br \/>\n<strong>Libert\u00e0 e internet:<\/strong><br \/>\ni giganti della rete cercherebbero di indebolire le normative europee di protezione dei dati personali per ridurli al livello quasi inesistente degli Stat Uniti, autorizzando in questo modo un accesso incontra stato alla privacy dei cittadini da parte delle imprese private<br \/>\n<strong>Democrazia:<\/strong><br \/>\nil trattato impedirebbe qualsiasi possibilit\u00e0 di scelta autonoma degli Stati in campo economico, sociale, ambientale, provocando la pi\u00f9 completa esautorazione di ogni intervento da parte degli enti locali<br \/>\n<strong>Biocombustibili:<\/strong><br \/>\nil TTIP attraverso l\u2019armonizzazione delle normative europee in ambito energetico, incentiverebbe l\u2019importazione di biomasse americane che non rispettano i limiti minimi di emissione di gas a effetto serra e altri criteri di sostenibilit\u00e0 ambientale.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcune ragioni per fermare il TTIP (Transatlantic Trade and Investment Partnership) il trattato di liberalizzazione commerciale tra UE e USA<\/p>\n","protected":false},"author":2,"featured_media":2115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16,38,44,9],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2113"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=2113"}],"version-history":[{"count":1,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2113\/revisions"}],"predecessor-version":[{"id":2116,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/2113\/revisions\/2116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/2115"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=2113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=2113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=2113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}