{"id":1025,"date":"2014-01-15T12:31:14","date_gmt":"2014-01-15T11:31:14","guid":{"rendered":"http:\/\/kuminda.org\/?p=1025"},"modified":"2014-01-15T12:31:14","modified_gmt":"2014-01-15T11:31:14","slug":"marinaleda-un-paese-dove-la-cooperazione-e-la-quotidianita","status":"publish","type":"post","link":"https:\/\/multiculturale.it\/kuminda\/2014\/01\/marinaleda-un-paese-dove-la-cooperazione-e-la-quotidianita\/","title":{"rendered":"Marinaleda: un paese dove la cooperazione \u00e8 la quotidianit\u00e0"},"content":{"rendered":"<p>Marinaleda \u00e8 un piccolo paese nel cuore dell&#8217;Andalusia che ha lottato contro un sistema capitalistico del mercato partendo dal lavoro comune e condiviso della terra. La loro bandiera riporta: &#8220;utopia verso la pace&#8221;.<!--more-->Riportiamo l&#8217;interessante inchiesta del quotidiano Repubblica pubblicata il giorno <a href=\"http:\/\/inchieste.repubblica.it\/it\/repubblica\/rep-it\/2013\/12\/27\/news\/marinaleda_il_paese_dove_non_esistono_disoccupati-74586848\/\">27 dicembre 2013 <\/a><\/p>\n<h3>&#8220;Nel cuore dell&#8217;Andalusia sorge una piccola comunit\u00e0 rurale che \u00e8 riuscita a sconfiggere la piaga dei senza lavoro. Un esempio unico nell&#8217;Europa colpita dalla crisi e dalla recessione creato dallo storico sindaco della cittadina. Juan Manuel S\u00e0nchez Gordillo ha fondato la politica economica e sociale su un principio che ha avuto successo: non pi\u00f9 copetivit\u00e0 ma cooperazione. Ispirandosi ai valori del socialismo reale ha costruito nell&#8217;arco di 30 anni un sistema che garantisce la sussistenza all&#8217;intera comunit\u00e0 agricola. Il risultato \u00e8 la piena occupazione e un sogno che resiste: l&#8217;utopia di un sistema di convivenza e produttivo diverso. Siamo andati a visitarlo. Ecco quello che abbiamo scoperto<\/h3>\n<p><strong>MARINALEDA &#8211;<\/strong> A poco pi\u00f9 di 100 chilometri da Siviglia, nel cuore dell&#8217;Andalusia, si trova una piccola comunit\u00e0 rurale di circa 2700 abitanti. Si chiama Marinaleda. Comune agricolocircondato da campi coltivati e migliaia di alberi di ulivo che si perdono all&#8217;orizzonte fin dove l&#8217;occhio pu\u00f2 arrivare. La particolarit\u00e0 di questo luog oapparentemente simile a molti altri delle aree interne al Mediterraneo, non \u00e8 il paesaggio e tanto meno la natura, ma la sua forza economica che lo rende unico. Qui la disoccupazione non esiste.<\/p>\n<p>Dal 1979, con le prime elezioni democratiche del post franchismo, a Marinaleda la giunta \u00e8 guidata dallo storico Alcalde, Juan Manuel S\u00e1nchez Gordillo. Additato come una specie di folle e anacronistico rivoluzionario, il sindaco ha basato la politica economica e sociale della comunit\u00e0 dandole una definizione molto chiara: utopia. Consapevole che l&#8217;unica forza in possesso della gente andalusa era la terra, fin dall&#8217;inizio ha guidato una campagna politica per ottenere una riforma agraria che permettesse a questo piccolo popolo di essere in grado di poter sostenere al meglio l&#8217;economia locale. Ed \u00e8 cos\u00ec che la maggior parte della popolazione \u00e8 impiegata in una grande cooperativa agricola perch\u00e9 qui non \u00e8 la competitivit\u00e0 il fondamento che regge l&#8217;economia, ma il suo esatto contrario: la cooperazione.<\/p>\n<p>Questo piccolo comune, ispirandosi agli ideali del socialismo reale, ha costruito nell&#8217;arco di 30 anni un sistema economico e sociale che garantisce la sussistenza dell&#8217;intera comunit\u00e0 e che ha permesso alla cittadina di reggere ai colpi della crisi economica che proprio in Andalusia ha prodotto negli ultimi anni gli effetti pi\u00f9 devastanti.<\/p>\n<p>Sulla bandiera tricolore, lo stemma al centro riporta la scritta &#8220;Marinaleda: una utopia verso la pace&#8221;. Juan Manuel Sanchez Gordillo, gi\u00e0 sindacalista dei lavoratori agricoli, capeggi\u00f2 dai primi anni 80 una mobilitazione per l&#8217;occupazione dei latifondi appartenenti ai grandi proprietari terrieri affinch\u00e9 fossero redistribuiti ai contadini senza terra. Una battaglia che nei primi anni 90 port\u00f2 alla cessionedel fondo El Humoso &#8211; 1.200 ettari di propriet\u00e0 di un nobile locale\u00a0 &#8211; all&#8217;Ayuntamiento di Marinaleda.<\/p>\n<p>Esperanza del Rosario Saavedra Martin &#8211; giovane e combattiva vice Alcalde &#8211; ci racconta che oggi, grazie alla cooperativa Humar, il 70% della popolazione residente ha un reddito sufficiente prodottodal lavoro nei campi e dall&#8217;industria della trasformazione. Il resto della popolazione lavora in piccoli esercizi commerciali e ovviamente qualche impiego pubblico in scuole e uffici.<\/p>\n<p>A Marinaleda si producono, conservano ed esportano peperoni, carciofi, legumi, olio d&#8217;oliva. La disoccupazione \u00e8 allo 0% contro il 30% di media nazionale e il 21% della provincia di Siviglia. Il salario \u00e8 lo stesso per tutti, qualunque sia la mansione: 47 euro al giorno per sei giorni la settimana. E se in qualche stagione i raccolti non vanno bene per via delle intemperie, si lavora meno ma si lavora tutti.<\/p>\n<p>Deputato del Parlamento Andaluso dal 2008 nel partito Izquierda Unida, il sindaco Sanchez Gordillo ha deciso di devolvere il suo compenso da parlamentare alla comunit\u00e0 di Marinaleda. Durante il discorso di insediamento ha pronunciato un giuramento inusuale lasciando sbigottita l&#8217;intera aula, impegnandosi a &#8220;lottare con ogni forza per sovvertire il sistema di produzione capitalistico e a ribellarsi alla dittatura del mercato, alle sue ricette e ai suoi mandati.&#8221;<\/p>\n<p>&#8220;Chi viene eletto in Municipio non percepisce nulla per il proprio incarico&#8221;, sottolinea la consigliera Esperanza, &#8220;quello che muove chi si presenta alle elezioni \u00e8 lo spirito di servizio verso la comunit\u00e0 e non l&#8217;ambizione personale&#8221;, aggiunge.<\/p>\n<p>Il sistema di welfare messo su negli anni permette ai cittadini di costruirsi una casa di 90 metri quadri con un anticipo di 15 euro. Basta mettere a disposizione la propria forza lavoro. Nessun mutuo e nessun interesse da versare ad istituti di credito: il terreno e il progetto li mette il Municipio, il denaro lo presta a tasso zero il governo andaluso e la quota mensile da versare per l&#8217;acquisto la decidono in assemblea gli stessi cittadini autocostruttori.<\/p>\n<p>Anche i servizi alla cittadinanza hanno un costo simbolico: la mensa scolastica costa 12 euro al mese, la piscina 3 euro per tutta l&#8217;estate. E la cura degli spazi comuni compete a tutti i cittadini: durante le cosiddette &#8220;domeniche rosse&#8221; ci si rimbocca le maniche dedicandosi a pulire strade, aiuole e giardini. La Polizia Locale non esiste e, manco a dirlo, non esiste la criminalit\u00e0. Come la disoccupazione.<\/p>\n<p>Nella Spagna stretta dalla morsa delle politiche di austerit\u00e0, Marinaleda ha risposto all&#8217;impatto della crisi peggiore che l&#8217;Europa abbia conosciuto nel dopoguerra con la costruzione di un tessuto sociale e vincoli di solidariet\u00e0. Vivere qui non \u00e8 semplice, ci raccontano alcuni lavoratori.\u00a0 &#8220;Il lavoro nei campi per noi \u00e8 parte integrante di un sistema che dura da 30 anni e non tutti sarebbero disposti ad accettare queste condizioni&#8221;. Ci vuole &#8220;volont\u00e0 politica, prima di tutto&#8221;, chiosa Esperanza.<\/p>\n<p>E a chi li accusa di essere dei pazzi fuori dal tempo e dall&#8217;economia globalizzata, arriva la risposta di una produzione agricola che oggi giunge sulle tavole di tutta la Spagna, di alcuni paesi europei\u00a0 &#8211;\u00a0 Italia compresa\u00a0 &#8211;\u00a0 fino al lontano Venezuela&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marinaleda \u00e8 un piccolo paese nel cuore dell&#8217;Andalusia che ha lottato contro un sistema capitalistico del mercato partendo dal lavoro comune e condiviso della terra. La loro bandiera riporta: &#8220;utopia verso la pace&#8221;.<\/p>\n","protected":false},"author":2,"featured_media":1026,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[24,10,16,36,35,42,34,38,44,13,9],"tags":[],"_links":{"self":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/1025"}],"collection":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/comments?post=1025"}],"version-history":[{"count":1,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/1025\/revisions"}],"predecessor-version":[{"id":1027,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/posts\/1025\/revisions\/1027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media\/1026"}],"wp:attachment":[{"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/media?parent=1025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/categories?post=1025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiculturale.it\/kuminda\/wp-json\/wp\/v2\/tags?post=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}